{"id":61252,"date":"2026-05-13T11:07:38","date_gmt":"2026-05-13T09:07:38","guid":{"rendered":"https:\/\/www.vidademadrid.com\/es\/?p=61252"},"modified":"2026-05-13T11:07:42","modified_gmt":"2026-05-13T09:07:42","slug":"guia-de-piscinas-de-verano-en-madrid-2026-donde-estan-entradas-y-apertura","status":"publish","type":"post","link":"https:\/\/www.vidademadrid.com\/es\/61252\/guia-de-piscinas-de-verano-en-madrid-2026-donde-estan-entradas-y-apertura\/","title":{"rendered":"Gu\u00eda de piscinas de verano en Madrid 2026: d\u00f3nde est\u00e1n, entradas y apertura"},"content":{"rendered":"<p>El verano est\u00e1 cada vez m\u00e1s cerca y las piscinas de la regi\u00f3n se preparan para abrir sus puertas para que los madrile\u00f1os disfruten de estas instalaciones. En esta gu\u00eda te proporcionamos toda la informaci\u00f3n sobre las\u00a0<strong>piscinas de verano en Madrid\u00a0<\/strong>para esta temporada de primavera-verano 2026.<\/p>\n<h2>Piscinas de verano Madrid 2026: fechas oficiales y horarios<\/h2>\n<p>El\u00a0<strong>Ayuntamiento de Madrid\u00a0<\/strong>ha anunciado que las piscinas municipales abrir\u00e1n sus puertas para este temporada el\u00a0<strong>15 de mayo<\/strong>, D\u00eda de San Isidro, que tendr\u00e1 una\u00a0<strong>jornada de puertas abiertas.\u00a0<\/strong>El horario de apertura ser\u00e1 de 10 a 21 horas. La temporada terminar\u00e1 el\u00a0<strong>domingo 6 de septiembre.\u00a0<\/strong><\/p>\n<p>Las piscinas de verano gestionadas por la\u00a0<strong>Comunidad de Madrid\u00a0<\/strong>(Puerta de Hierro, San Vicente de Paul, Canal de Isabel II y Mundial 86) abrir\u00e1n del\u00a0<strong>15 de mayo al 6 de septiembre. <\/strong>El horario ser\u00e1 de 11 a 20 horas.<\/p>\n<p>Por otro lado, la\u00a0<strong>piscina de verano de la Complutense\u00a0<\/strong>abrir\u00e1 del\u00a0<strong>1 de junio al 8 de septiembre\u00a0<\/strong>de 11 a 20.30 horas.<\/p>\n<h2>Piscinas de verano Madrid 2026: precios, entradas y c\u00f3mo reservar<\/h2>\n<div class=\"td-pb-span8 td-main-content\" role=\"main\">\n<div class=\"td-ss-main-content\">\n<article id=\"post-59363\" class=\"post-59363 post type-post status-publish format-standard has-post-thumbnail category-actualidad-noticias-madrid category-destacados category-madrid-hoy category-aire-libre\">\n<div class=\"td-post-content tagdiv-type\">\n<h3>Piscinas del Ayuntamiento de Madrid<\/h3>\n<p>Este a\u00f1o, volver\u00e1n\u00a0<strong>los tres turnos:\u00a0<\/strong>uno de ma\u00f1ana (10:00 a 15:00 horas), uno de tarde (16:00 a 21:00 horas) y uno de d\u00eda completo (10:00 a 21:00 horas), y los <strong>c\u00f3digos QR\u00a0<\/strong>en la entrada y salida de las instalaciones. Las entradas de d\u00eda completo permiten salir y volver a entrar en el mismo d\u00eda y a las personas que adquieran este turno se les facilitar\u00e1 una\u00a0<strong>pulsera identificativa,\u00a0<\/strong>intransferible y v\u00e1lida para el d\u00eda de su adquisici\u00f3n.<\/p>\n<p>Es necesario reservar previamente para la\u00a0<strong>piscinas municipales de Madrid.\u00a0<\/strong>Se reserva en esta\u00a0<a href=\"https:\/\/deportesweb.madrid.es\/DeportesWeb\/login\">web<\/a>, es necesario tener cuenta, o a trav\u00e9s de la app\u00a0<em>Madrid M\u00f3vil<\/em> seleccionado la opci\u00f3n <em>&#8216;Entradas de uso libre &gt; piscina de verano&#8217;<\/em>.<\/p>\n<p>Las entradas se podr\u00e1n comprar una antelaci\u00f3n de 45 horas al turno solicitado y en ambo, se pondr\u00e1 a la venta el 80% de las entradas, quedando el 20% restante para su venta en las taquillas de cada centro deportivo 30 minutos antes del comienzo del turno.<\/p>\n<p>Las entradas en taquilla est\u00e1n reservadas para aquellas personas afectadas por la brecha tecnol\u00f3gica, como los mayores de 65 a\u00f1os, poseedores de la tarjeta madridmayor.es y titulares del carn\u00e9 de deporte especial.<\/p>\n<p>Los\u00a0<strong>precios para los turnos de ma\u00f1ana o tarde\u00a0<\/strong>son:<\/p>\n<ul>\n<li>Menor de 5 a\u00f1os: gratis<\/li>\n<li>Infantil (de 5 a 14 a\u00f1os): 1,35 euros<\/li>\n<li>Joven (15 a 26 a\u00f1os): 1,80 euros<\/li>\n<li>Adulto (27 a 64 a\u00f1os): 2,25 euros<\/li>\n<li>Mayor (a partir de 65 a\u00f1os): 0,70 euros<\/li>\n<\/ul>\n<p>Los\u00a0<strong>precios para el d\u00eda completo\u00a0<\/strong>son:<\/p>\n<ul>\n<li>Menor de 5 a\u00f1os: gratis<\/li>\n<li>Infantil (de 5 a 14 a\u00f1os): 2,70 euros<\/li>\n<li>Joven (15 a 26 a\u00f1os): 3,60 euros<\/li>\n<li>Adulto (de 27 a 64 a\u00f1os): 4,50 euros<\/li>\n<li>Mayor (a partir de 65 a\u00f1os): 1,35 euros<\/li>\n<\/ul>\n<h3>Piscinas de la Comunidad de Madrid<\/h3>\n<p>Las entradas para las cuatro piscinas gestionadas por la\u00a0<strong>Comunidad de Madrid\u00a0<\/strong>se podr\u00e1n reservar en este\u00a0<a href=\"https:\/\/gestiona3.madrid.org\/cronosweb\/Login\">enlace<\/a>\u00a0o a trav\u00e9s de la app\u00a0<em>DeportesCM.\u00a0<\/em><\/p>\n<p>Los precios ser\u00e1n los mismos que el a\u00f1o pasado: 5 \u20ac por sesi\u00f3n.<\/p>\n<ul>\n<li>Gratis para las personas que acrediten un grado de discapacidad reconocida igual o superior al 33%, tambi\u00e9n sus acompa\u00f1antes, as\u00ed como para los menores de 3 a\u00f1os y las v\u00edctimas del terrorismo; gratis para titulares del Carn\u00e9 Joven en San Vicente Paul, Parque Deportivo Puerta de Hierro y Canal de Isabel II.<\/li>\n<li>20% para titulares del Carn\u00e9 Joven en M86. 30% descuento para mayores de 65 a\u00f1os de edad, los ni\u00f1os entre los 3 y los 13 a\u00f1os de edad inclusive y los miembros pertenecientes a familias numerosas.<\/li>\n<\/ul>\n<h3>Piscinas de verano de la Universidad Complutense<\/h3>\n<p>La\u00a0<strong>piscina de verano de la Universidad Complutense<\/strong>\u00a0tendr\u00e1 este 2025 estos precios: 4,50 \u20ac para Personal, Estudiantes y Alumni UCM (bono 10 ba\u00f1os: 25 \u20ac); 6 \u20ac para no vinculados UCM (bono 10 ba\u00f1os: 50 \u20ac).<\/p>\n<h2>Piscinas de verano Madrid 2025: listado de piscinas municipales abiertas<\/h2>\n<p>Las piscinas municipales que abrir\u00e1n este 15 de mayo son:<\/p>\n<ul>\n<li>Barajas: CDM Mistas \u2013 C\/ Mistral, 4<\/li>\n<li>Carabanchel: CDM Blanca Fern\u00e1ndez Ochoa \u2013 C\/ Monse\u00f1or Oscar Romero, 41<\/li>\n<li>Ciudad Lineal: CDM Concepci\u00f3n \u2013 C\/ Jos\u00e9 del Hierro, 5<\/li>\n<li>Fuencarral-El Pardo: CDM Santa Ana \u2013 Paseo Alamedillas, 5<\/li>\n<li>Hortaleza: CDM Hortaleza \u2013 Ctra. a la Estaci\u00f3n de Hortaleza, 11<\/li>\n<li>Latina: CDM Aluche \u2013 Avda. General Fanjul, 14<\/li>\n<li>Moncloa-Aravaca: CDM Casa de Campo \u2013 P\u00ba Puerta del \u00c1ngel, 7<\/li>\n<li>Moncloa-Aravaca: CDM El Quijote \u2013 C\/ Numancia, 11<\/li>\n<li>Moncloa-Aravaca: CDM Jos\u00e9 Mar\u00eda Cagigal \u2013 C\/ Santa Pola, 22<\/li>\n<li>Moratalaz: CDM La Elipa \u2013 C\/ Alcalde Garrido Juaristi, s\/n<\/li>\n<li>Moratalaz: CDM Moratalaz \u2013 C\/ Valdebernardo, 2<\/li>\n<li>Pe\u00f1uelas (APERTURA EL 19 DE JULIO): C\/ Arganda, 25<\/li>\n<li>Puente de Vallecas: CDM Entrev\u00edas \u2013 C\/ Ronda del Sur, 4<\/li>\n<li>Puente de Vallecas: CDM Palomeras \u2013 C\/ Tranv\u00eda de Arganda, 4<\/li>\n<li>San Blas-Canillejas: CDM San Blas \u2013 C\/ Arcos del Jal\u00f3n, 59<\/li>\n<li>Tetu\u00e1n: CDM Paseo de la Direcci\u00f3n \u2013 P\u00ba de la Direcci\u00f3n, 125<\/li>\n<li>Usera: CDM Orcasitas \u2013 Avda. Rafaela Ybarra, 52<\/li>\n<li>Usera: CDM San Ferm\u00edn \u2013 C\/ San Mario, 18<\/li>\n<li>Vic\u00e1lvaro: CDM Margot Moles \u2013 P\u00ba del Polideportivo, 3<\/li>\n<li>Villa de Vallecas: CDM Cerro Almod\u00f3var \u2013 C\/ del Cerro de Almod\u00f3var, 9<\/li>\n<li>Villaverde: CDM Plata y Casta\u00f1ar \u2013 P\u00ba de la Plata y Casta\u00f1ar, 7<\/li>\n<\/ul>\n<p>Algunas de las piscinas municipales se encuentran en obras y se prev\u00e9 que abran sus instalaciones en el mes de julio de 2025. Los centros deportivos municipales que se encuentran en obras son:<\/p>\n<ul>\n<li>Luis Aragon\u00e9s (Hortaleza)<\/li>\n<li>Pe\u00f1uelas (Arganzuela)<\/li>\n<li>Vicente del Bosque (Fuencarral-El Pardo)<\/li>\n<li>Moscard\u00f3 (Usera)<\/li>\n<li>Orcasitas (Usera)<\/li>\n<\/ul>\n<h2>Piscinas de la Comunidad de Madrid 2025<\/h2>\n<ul>\n<li>Canal de Isabel II \u2013 Avda. de Filipinas, 54<\/li>\n<li>Parque Deportivo Puerta de Hierro \u2013 Crta. de la Coru\u00f1a, km. 7<\/li>\n<li>San Vicente de Pa\u00fal \u2013 Calle Pel\u00edcano, 4<\/li>\n<li>Centro Deportivo Mundial 86 \u2013 C\/ Jos\u00e9 Mart\u00ednez de Velasco, 3<\/li>\n<\/ul>\n<p>Adem\u00e1s, la\u00a0<strong>Comunidad de Madrid\u00a0<\/strong>cuenta con cuatro zonas naturales aptas para el ba\u00f1o durante el verano:<\/p>\n<ul>\n<li>Embalse de San Juan (San Mart\u00edn de Valdeiglesias)<\/li>\n<li>Playa de Alberche (Aldea del Fresno)<\/li>\n<li>Las Presillas (Rascafr\u00eda)<\/li>\n<li>Los Villares (Estremera)<\/li>\n<\/ul>\n<h3>Piscinas de verano de la Universidad Complutense<\/h3>\n<p>La piscina de verano de la\u00a0<strong>Universidad Complutense\u00a0<\/strong>est\u00e1 ubicada en el Complejo Deportivo Zona Sur (Avda. Juan de Herrera) de la universidad.<\/p>\n<\/div>\n<\/article>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>La temporada empezar\u00e1 el viernes 15 de mayo con una jornada de puertas abiertas. <\/p>\n","protected":false},"author":15,"featured_media":33120,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12,78],"tags":[],"class_list":{"0":"post-61252","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-actualidad-noticias-madrid","8":"category-deporte"},"_links":{"self":[{"href":"https:\/\/www.vidademadrid.com\/es\/wp-json\/wp\/v2\/posts\/61252","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vidademadrid.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vidademadrid.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vidademadrid.com\/es\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vidademadrid.com\/es\/wp-json\/wp\/v2\/comments?post=61252"}],"version-history":[{"count":2,"href":"https:\/\/www.vidademadrid.com\/es\/wp-json\/wp\/v2\/posts\/61252\/revisions"}],"predecessor-version":[{"id":61254,"href":"https:\/\/www.vidademadrid.com\/es\/wp-json\/wp\/v2\/posts\/61252\/revisions\/61254"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vidademadrid.com\/es\/wp-json\/wp\/v2\/media\/33120"}],"wp:attachment":[{"href":"https:\/\/www.vidademadrid.com\/es\/wp-json\/wp\/v2\/media?parent=61252"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vidademadrid.com\/es\/wp-json\/wp\/v2\/categories?post=61252"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vidademadrid.com\/es\/wp-json\/wp\/v2\/tags?post=61252"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}