{"id":56121,"date":"2024-05-03T11:43:34","date_gmt":"2024-05-03T09:43:34","guid":{"rendered":"https:\/\/www.vidademadrid.com\/es\/?p=56121"},"modified":"2024-05-06T00:51:43","modified_gmt":"2024-05-05T22:51:43","slug":"cierre-linea-c9-cercanias-obras-renovacion-autobuses-alternativos","status":"publish","type":"post","link":"https:\/\/www.vidademadrid.com\/es\/56121\/cierre-linea-c9-cercanias-obras-renovacion-autobuses-alternativos\/","title":{"rendered":"La l\u00ednea C-9 de Cercan\u00edas cerrar\u00e1 un a\u00f1o por obras de renovaci\u00f3n"},"content":{"rendered":"<p>La&nbsp;<strong>l\u00ednea C-9 de Cercan\u00edas,&nbsp;<\/strong>entre Cercedilla y Cotos, cerrar\u00e1 durante un a\u00f1o por la&nbsp;<strong>renovaci\u00f3n integral&nbsp;<\/strong>de su infraestructura. Habr\u00e1 un servicio alternativo para los viajeros que necesiten realizar ese trayecto.<\/p>\n<h2>Cierre de la C-9 de Cercan\u00edas<\/h2>\n<p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script> <ins class=\"adsbygoogle\" style=\"display:block\" data-ad-format=\"fluid\" data-ad-layout-key=\"-7f+eo+1+2-5\" data-ad-client=\"ca-pub-7450064428034605\" data-ad-slot=\"7327027071\"><\/ins><script>(adsbygoogle = window.adsbygoogle || []).push({});<\/script>Los trenes de la&nbsp;<strong>C-9 de Cercan\u00edas,<\/strong> que va de Cercedilla a Cotos con parada en el Puerto de Navacerrada, har\u00e1n su \u00faltimo trayecto el&nbsp;<strong>3 de mayo&nbsp;<\/strong>antes de su cierre por&nbsp;<strong>un a\u00f1o&nbsp;<\/strong>por la&nbsp;<strong>renovaci\u00f3n integral de la infraestructura&nbsp;<\/strong>y&nbsp;<strong>de las estaciones.&nbsp;<\/strong><\/p>\n<p>Las obras de la&nbsp;<strong>C-9&nbsp;<\/strong>supondr\u00e1n la reapertura del servicio con nuevos trenes: seis unidades alpinas que ya est\u00e1 construyendo CAF que est\u00e1n compuestas por dos coches, disponen de los \u00faltimos avances tecnol\u00f3gicos y de accesibilidad y confort a bordo adem\u00e1s de espacio para bicicletas, mochilas y esqu\u00edes.&nbsp;<\/p>\n<p>Estos nuevos trenes permitir\u00e1n aumentar la frecuencia de la l\u00ednea e incrementar el n\u00famero de viajeros por trayecto.&nbsp;<\/p>\n<h2>Servicio alternativo de autob\u00fas<\/h2>\n<p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script> <ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-7450064428034605\" data-ad-slot=\"5670045061\"><\/ins> <script>(adsbygoogle = window.adsbygoogle || []).push({});<\/script>Para garantizar la movilidad de los usuarios se ha activado un <strong>servicio alternativo de trasporte por carretera&nbsp;<\/strong>que realizar\u00e1 las mismas paradas que el tren. Lo podr\u00e1n utilizar los portadores de un t\u00edtulo de transporte v\u00e1lido para viajar en la zona C2, as\u00ed como poseedores del abono recurrente, siempre que se haya reservado plaza previamente.&nbsp;<\/p>\n<p>El trayecto entre&nbsp;<strong>Cercedilla y Cotos,&nbsp;<\/strong>con parada en el Puerto de Navacerrada, tendr\u00e1n a su disposici\u00f3n un servicio especial de autobuses que har\u00e1&nbsp;<strong>cinco idas y cinco vueltas cada d\u00eda.&nbsp;<\/strong><\/p>\n<p>El primer autob\u00fas partir\u00e1 diariamente de la estaci\u00f3n de Cercedilla a las 9.35 horas y el \u00faltimo saldr\u00e1 de Cotos a las 18.45 horas.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Habr\u00e1 un servicio especial de autobuses. <\/p>\n","protected":false},"author":15,"featured_media":53388,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[187,23],"tags":[],"class_list":{"0":"post-56121","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-madrid-hoy","8":"category-transportes-huelgas-madrid"},"_links":{"self":[{"href":"https:\/\/www.vidademadrid.com\/es\/wp-json\/wp\/v2\/posts\/56121","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vidademadrid.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vidademadrid.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vidademadrid.com\/es\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vidademadrid.com\/es\/wp-json\/wp\/v2\/comments?post=56121"}],"version-history":[{"count":2,"href":"https:\/\/www.vidademadrid.com\/es\/wp-json\/wp\/v2\/posts\/56121\/revisions"}],"predecessor-version":[{"id":56123,"href":"https:\/\/www.vidademadrid.com\/es\/wp-json\/wp\/v2\/posts\/56121\/revisions\/56123"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vidademadrid.com\/es\/wp-json\/wp\/v2\/media\/53388"}],"wp:attachment":[{"href":"https:\/\/www.vidademadrid.com\/es\/wp-json\/wp\/v2\/media?parent=56121"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vidademadrid.com\/es\/wp-json\/wp\/v2\/categories?post=56121"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vidademadrid.com\/es\/wp-json\/wp\/v2\/tags?post=56121"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}