{"id":53346,"date":"2023-11-02T12:29:41","date_gmt":"2023-11-02T11:29:41","guid":{"rendered":"https:\/\/www.vidademadrid.com\/es\/?p=53346"},"modified":"2023-11-02T12:29:45","modified_gmt":"2023-11-02T11:29:45","slug":"el-rey-leon-temporada-navidena-entradas-2023","status":"publish","type":"post","link":"https:\/\/www.vidademadrid.com\/es\/53346\/el-rey-leon-temporada-navidena-entradas-2023\/","title":{"rendered":"Disfruta del exitoso musical \u00abEl Rey Le\u00f3n\u00bb estas Navidades\u00a0"},"content":{"rendered":"<p>La&nbsp;<strong>Gran V\u00eda de Madrid&nbsp;<\/strong>alberga los mejores musicales. El m\u00e1s exitoso de estos, que lleva ya 12 temporadas, es <strong>El Rey Le\u00f3n: el musical,&nbsp;<\/strong>un plan para disfrutar con familia o amigos estas Navidades.&nbsp;<\/p>\n<h2>El Rey Le\u00f3n: el musical en Gran V\u00eda&nbsp;<\/h2>\n<p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script> <ins class=\"adsbygoogle\" style=\"display:block\" data-ad-format=\"fluid\" data-ad-layout-key=\"-7f+eo+1+2-5\" data-ad-client=\"ca-pub-7450064428034605\" data-ad-slot=\"7327027071\"><\/ins><script>(adsbygoogle = window.adsbygoogle || []).push({});<\/script><strong>El Rey Le\u00f3n: el musical&nbsp;<\/strong>transporta a los espectadores a la sabana africana a trav\u00e9s de su sorprendente puesta en escena que, junto con esculturas animadas, m\u00fasica evocadora y una interpretaci\u00f3n inigualable.&nbsp;<\/p>\n<p>Con canciones de Elton John y Tim Rice as\u00ed como la visi\u00f3n musical de Lebo M. y Hans Zimmer.&nbsp;<strong>El Rey Le\u00f3n: el musical&nbsp;<\/strong>cuenta con un elenco compuesto por m\u00e1s de&nbsp;<strong>50 actores&nbsp;<\/strong>de diferentes pa\u00edses.&nbsp;<\/p>\n<p>Este musical lleg\u00f3 a Broadway en 1997 y tuvo su primera funci\u00f3n en Madrid en 2011 y lo han visto m\u00e1s de <strong>110 millones de espectadores en todo el mundo,<\/strong> 6 de ellos en Madrid. El musical se ha presentado en&nbsp;<strong>18 pa\u00edses y se ha traducido a 8 idiomas.&nbsp;<\/strong><\/p>\n<h2>El Rey Le\u00f3n: el musical en Madrid: entradas&nbsp;<\/h2>\n<p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script> <ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-7450064428034605\" data-ad-slot=\"5670045061\"><\/ins> <script>(adsbygoogle = window.adsbygoogle || []).push({});<\/script><strong>El Rey Le\u00f3n: el musical&nbsp;<\/strong>est\u00e1 en el&nbsp;<strong>Teatro Lope de Vega&nbsp;<\/strong>en Gran V\u00eda. Las entradas para la temporada navide\u00f1a ya est\u00e1n disponibles y se pueden adqurir las <strong>entradas<\/strong> o&nbsp;<strong>entradas + hotel.&nbsp;<\/strong><\/p>\n<p>Las entradas van desde los 24 euros y se pueden adquirir en este <a href=\"https:\/\/www.stage.es\/musicales\/el-rey-leon\/entradas\">enlace<\/a>.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se encuentra en su 12\u00ba temporada. <\/p>\n","protected":false},"author":15,"featured_media":53347,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[111],"tags":[],"class_list":{"0":"post-53346","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-exposiciones-madrid"},"_links":{"self":[{"href":"https:\/\/www.vidademadrid.com\/es\/wp-json\/wp\/v2\/posts\/53346","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vidademadrid.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vidademadrid.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vidademadrid.com\/es\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vidademadrid.com\/es\/wp-json\/wp\/v2\/comments?post=53346"}],"version-history":[{"count":2,"href":"https:\/\/www.vidademadrid.com\/es\/wp-json\/wp\/v2\/posts\/53346\/revisions"}],"predecessor-version":[{"id":53349,"href":"https:\/\/www.vidademadrid.com\/es\/wp-json\/wp\/v2\/posts\/53346\/revisions\/53349"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vidademadrid.com\/es\/wp-json\/wp\/v2\/media\/53347"}],"wp:attachment":[{"href":"https:\/\/www.vidademadrid.com\/es\/wp-json\/wp\/v2\/media?parent=53346"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vidademadrid.com\/es\/wp-json\/wp\/v2\/categories?post=53346"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vidademadrid.com\/es\/wp-json\/wp\/v2\/tags?post=53346"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}