{"id":193,"count":31,"description":"","link":"https:\/\/www.vidademadrid.com\/es\/agenda-del-mes-madrid\/","name":"Agenda del mes","slug":"agenda-del-mes-madrid","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/www.vidademadrid.com\/es\/wp-json\/wp\/v2\/categories\/193","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vidademadrid.com\/es\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.vidademadrid.com\/es\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.vidademadrid.com\/es\/wp-json\/wp\/v2\/posts?categories=193"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}